{"id":6118,"date":"2014-01-07T00:40:01","date_gmt":"2014-01-07T03:40:01","guid":{"rendered":"http:\/\/www.ligavpg.com\/blog\/?page_id=6118"},"modified":"2014-01-09T00:16:25","modified_gmt":"2014-01-09T03:16:25","slug":"hotlaps","status":"publish","type":"page","link":"https:\/\/www.ligavpg.com\/blog\/servidores\/hotlaps\/","title":{"rendered":"Hotlaps"},"content":{"rendered":"<table class=\"table-bordered\">\n<thead>\n<tr>\n<th colspan=\"2\">\n<h4>Hotlaps da Liga VPG<\/h4>\n<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Entre em um dos nossos servidores e registre o seu tempo.*Os tempos apenas s\u00e3o computados ap\u00f3s o avan\u00e7o de sess\u00e3o.<br \/>\n*<b>QUALQUER PILOTO<\/b>\u00a0que completar voltas registrar\u00e1 tempo, depois \u00e9 s\u00f3 comparar com os demais pilotos.<br \/>\n* Para entrar em um dos nossos servidores, basta o piloto ter o MOD da Liga VPG instalado.<br \/>\n* Cadastre-se no nosso f\u00f3rum e obtenha todas as informa\u00e7\u00f5es.<\/td>\n<td style=\"text-align: center;\"><a title=\"Tela Cheia\" href=\"http:\/\/www.ligavpg.com\/hotlaps\/HotLaps.php\" target=\"_blank\"><img decoding=\"async\" style=\"vertical-align: middle;\" title=\"Tela Cheia\" alt=\"Tela Cheia\" src=\"http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/icon-fullscreen.png\" width=\"45\" height=\"45\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table>\n<tbody>\n<tr>\n<td>\n<p align=\"center\"><iframe id=\"the_iframe\" src=\"http:\/\/www.ligavpg.com\/hotlaps\/HotLaps.php\" height=\"2600\" width=\"1100\" frameborder=\"0\" scrolling=\"auto\"><\/iframe><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Hotlaps da Liga VPG Entre em um dos nossos servidores e registre o seu tempo.*Os tempos apenas s\u00e3o computados ap\u00f3s o avan\u00e7o de sess\u00e3o. *QUALQUER PILOTO\u00a0que completar voltas registrar\u00e1 tempo, depois \u00e9 s\u00f3 comparar com os demais pilotos. * Para entrar em um dos nossos servidores, basta o piloto ter o MOD da Liga VPG [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":6110,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-6118","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/6118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/comments?post=6118"}],"version-history":[{"count":8,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/6118\/revisions"}],"predecessor-version":[{"id":6234,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/6118\/revisions\/6234"}],"up":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/pages\/6110"}],"wp:attachment":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/media?parent=6118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}