{"id":16370,"date":"2023-07-16T22:49:54","date_gmt":"2023-07-17T01:49:54","guid":{"rendered":"https:\/\/www.ligavpg.com\/blog\/?p=16370"},"modified":"2023-07-16T22:49:54","modified_gmt":"2023-07-17T01:49:54","slug":"acao-intensa-na-4a-etapa-da-bmw-m4-gt3-em-gateway","status":"publish","type":"post","link":"https:\/\/www.ligavpg.com\/blog\/acao-intensa-na-4a-etapa-da-bmw-m4-gt3-em-gateway\/","title":{"rendered":"A\u00e7\u00e3o intensa na 4\u00aa etapa da BMW M4 GT3 em Gateway &#x1f3c1;&#x1f525;"},"content":{"rendered":"<p style=\"text-align: justify;\">A 4\u00aa etapa da categoria BMW M4 GT3 proporcionou momentos emocionantes no circuito de Gateway Motorsports Park, um tra\u00e7ado desafiador que mescla trechos oval e interno. Foi um verdadeiro espet\u00e1culo de velocidade e habilidade, mas tamb\u00e9m marcado por acidentes espetaculares.<\/p>\n<p style=\"text-align: justify;\">Na primeira bateria, Adriano Max, da equipe Viracopos Gold, conquistou a vit\u00f3ria em uma corrida eletrizante de 25 minutos. Largando da 4\u00aa posi\u00e7\u00e3o, o piloto lutou e ganhou posi\u00e7\u00f5es, assumindo a dianteira na 10\u00aa volta e mantendo-se \u00e0 frente at\u00e9 o final. Leonardo Sampaio, da LM Racing, tamb\u00e9m teve uma atua\u00e7\u00e3o impressionante, cruzando a linha de chegada em 2\u00ba lugar ap\u00f3s largar na 5\u00aa posi\u00e7\u00e3o. Joe Silvestrini, da Fanatic Brasil, completou o p\u00f3dio em 3\u00ba lugar, mostrando seu talento ao sair da 6\u00aa posi\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A prova foi marcada por intensas disputas ao longo das voltas, com Andre Krasauskas, da Team_Schnell, terminando em 4\u00ba lugar e Alessandro Moraes, da Tornado e-Motorsports, fechando o top five. Destaque para Ricardo Soeiro, da equipe Viracopos Gold, que ganhou impressionantes 10 posi\u00e7\u00f5es ao longo da corrida.<\/p>\n<p style=\"text-align: justify;\">A segunda bateria trouxe ainda mais emo\u00e7\u00e3o, com a invers\u00e3o do grid nas 10 primeiras posi\u00e7\u00f5es. Apesar de um acidente no in\u00edcio da corrida que impactou muitos pilotos, Erick Souza, da equipe CBR Team, mostrou determina\u00e7\u00e3o e habilidade ao conquistar sua primeira vit\u00f3ria na Liga VPG. Bruno Adolfo Hoffmann, da Viracopos Gold, fez uma excelente prova, garantindo o 2\u00ba lugar com uma pequena diferen\u00e7a de tempo para o l\u00edder. Edilson Freshi, da Tornado e-Motorsports, se recuperou ap\u00f3s um in\u00edcio de noite desastrosa e cruzou a linha de chegada em 3\u00ba lugar.<\/p>\n<p style=\"text-align: justify;\">Fechando o top five, Fernando Bergesch se destacou com impressionantes 13 ultrapassagens, cruzando a linha de chegada em 4\u00ba lugar. Leandro Roveda, da Tornado e-Motorsports, fez uma prova consistente e garantiu o 5\u00ba lugar.<\/p>\n<p style=\"text-align: justify;\">A final do campeonato est\u00e1 marcada para o dia 17\/07 no circuito de \u00cdmola, prometendo muitas ultrapassagens, estrat\u00e9gias e emo\u00e7\u00e3o. N\u00e3o perca nenhum lance e acompanhe a transmiss\u00e3o ao vivo da <a href=\"https:\/\/www.youtube.com\/watch?v=Q3wsutqHa70\" target=\"_blank\" rel=\"noopener\">Elleven TV<\/a> . Esteja preparado para presenciar momentos emocionantes e decisivos. &#x1f6a6;&#x1f525;<\/p>\n<p>&nbsp;<\/p>\n<p>Confira os resultados completos da quarta etapa:<\/p>\n<ul>\n<li><a href=\"http:\/\/slsligavpg.servegame.com\/index.php?dataarray%5Bdest%5D=resevent&amp;dataarray%5Bshownicks%5D=1&amp;dataarray%5BIDrace%5D=1161&amp;dataarray%5BIDseason%5D=171\" target=\"_blank\" rel=\"noopener\">1\u00aa Bateria<\/a><\/li>\n<li><a href=\"http:\/\/slsligavpg.servegame.com\/index.php?dataarray%5Bdest%5D=resevent&amp;dataarray%5Bshownicks%5D=1&amp;dataarray%5BIDrace%5D=1162&amp;dataarray%5BIDseason%5D=171\" target=\"_blank\" rel=\"noopener\">2\u00aa Bateria<\/a><\/li>\n<li><a href=\"http:\/\/slsligavpg.servegame.com\/index.php?dataarray%5BIDseason%5D=171&amp;dataarray%5Bdest%5D=standdrv\" target=\"_blank\" rel=\"noopener\">Classifica\u00e7\u00e3o Geral<\/a><\/li>\n<li><a href=\"http:\/\/slsligavpg.servegame.com\/index.php?dataarray%5BIDseason%5D=171&amp;dataarray%5Bdest%5D=standteam\" target=\"_blank\" rel=\"noopener\">Classifica\u00e7\u00e3o por Equipes<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=XH3ylzg4l70\" target=\"_blank\" rel=\"noopener\">Transmiss\u00e3o Ao Vivo da prova de Gateway<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Emo\u00e7\u00e3o e ultrapassagens incr\u00edveis na 4\u00aa etapa em Gateway com Adriano Max e Erick Souza conquistando vit\u00f3rias incr\u00edveis. Confira mais detalhes.<\/p>\n","protected":false},"author":7,"featured_media":16371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[483,481],"tags":[37,210,38,489,44,35,152],"class_list":["post-16370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bmw-m4-gt3","category-vpg-2023","tag-automobilismo-virtual","tag-bmw","tag-corridas-virtuais","tag-gateway","tag-pilotos-virtuais","tag-rfactor2","tag-simracing"],"_links":{"self":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/16370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/comments?post=16370"}],"version-history":[{"count":1,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/16370\/revisions"}],"predecessor-version":[{"id":16372,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/16370\/revisions\/16372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/media\/16371"}],"wp:attachment":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/media?parent=16370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/categories?post=16370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/tags?post=16370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}