{"id":2374,"date":"2011-03-12T23:48:41","date_gmt":"2011-03-13T02:48:41","guid":{"rendered":"http:\/\/www.ligavpg.com\/blog\/?p=2374"},"modified":"2011-03-23T00:07:00","modified_gmt":"2011-03-23T03:07:00","slug":"jeferson-richart-brilha-em-obera-pela-3a-etapa-da-challenge","status":"publish","type":"post","link":"https:\/\/www.ligavpg.com\/blog\/jeferson-richart-brilha-em-obera-pela-3a-etapa-da-challenge\/","title":{"rendered":"Jeferson Richart brilha em Ober\u00e1 pela 3a etapa da Challenge!"},"content":{"rendered":"<table style=\"height: 200px;\" border=\"0\" width=\"600\">\n<tbody>\n<tr>\n<td>\n<div style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-2390\" title=\"T01_2011_3_etapa_Obera_Challenge\" src=\"http:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/T01_2011_3_etapa_Obera_Challenge.jpg\" alt=\"\" width=\"600\" height=\"375\" srcset=\"https:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/T01_2011_3_etapa_Obera_Challenge.jpg 600w, https:\/\/www.ligavpg.com\/blog\/wp-content\/uploads\/T01_2011_3_etapa_Obera_Challenge-300x187.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n<div style=\"text-align: justify;\">\n<p><strong><span style=\"color: #000000;\">Jeferson Richart brilha em Ober\u00e1 pela 3a etapa da Challenge!<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">Numa corrida muito disputada, com os 3 primeiros trocando de posi\u00e7\u00f5es durante a prova e sempre andando bem pr\u00f3ximos, Jeferson Richart se torna o 3o vencedor diferente nas 3 etapas ocorridas da categoria Challenge, e assume a lideran\u00e7a do campeonato.<\/span><\/p>\n<p><span style=\"color: #000000;\">Como acontece frequentemente, nos treinos o dom\u00ednio foi de Sammarone. Mas Jeferson j\u00e1 demonstrou a sua for\u00e7a quando no qualify ficou com a pole, deixando Sammarone em 2o. Ernesto Brock (3o), Jonatan Richart (4o), Thiago Santos (5o) e Leonardo Sampaio (6o) completam as 3 primeiras filas do grid.<\/span><\/p>\n<p><span style=\"color: #000000;\">S\u00f3 que na largada, Jeferson deixou escapar a vantagem obtida no qualy, largando mal e perdendo a lideran\u00e7a antes da curva 1 para Sammarone. Brock tb larga muito bem, mas Jeferson se mant\u00e9m na defensiva e Brock n\u00e3o consegue a ultrapassagem. Maurino J\u00fanior, 10o no grid, larga forte mas na curva 1 se envolve em um incidente com Marcello Menescal que acaba causando uma confus\u00e3o que sobra para v\u00e1rios pilotos. Valdir Nogueira (18o), Marcello Menescal (19o), Spont\u00e3o (20o) e F\u00e1bio N\u00e9ris (21o) caem para as \u00faltimas posi\u00e7\u00f5es. F\u00e1bio abandona antes de terminar a 1a volta.<\/span><\/p>\n<\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">As primeiras voltas s\u00e3o muito disputadas em todos os pelot\u00f5es, e sob alta press\u00e3o alguns pilotos acabam cometendo erros e perdendo posi\u00e7\u00f5es, como Luiz Bezerra, que cai para 14o, e Helder M\u00fcller, que cai para 19o. Enquanto isso, Sammarone lidera com Jeferson muito pr\u00f3ximo e Brock um pouco atr\u00e1s. Durante a 6a volta, a conex\u00e3o de Allan Guerra (15o) cai e ele abandona.<\/span>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">No final da 7a volta Cac\u00e1 Santos, Beto M\u00fcller e Thiago Santos disputam a 5a posi\u00e7\u00e3o, mas eles se envolvem em um incidente na \u00faltima curva que acaba beneficiando Jonatan Richart, que vinha em 8o e pula para 5o. Thiago se mant\u00e9m na pista em 6o mas Cac\u00e1 e Beto caem para a 10a e 11a posi\u00e7\u00f5es. O carro de Beto fica muito danificado, e ele luta para dar mais uma volta e levar seu carro para os boxes, caindo para a \u00faltima posi\u00e7\u00e3o (19o). Na volta seguinte ele para novamente.<\/span><\/p>\n<p><span style=\"color: #000000;\">Na 11a volta come\u00e7am as paradas regulares dos pilotos do final do pelot\u00e3o. Na volta seguinte os l\u00edderes Sammarone e Jeferson tamb\u00e9m param, passando a lideran\u00e7a para Brock e a 2a posi\u00e7\u00e3o para Leonardo Sampaio, at\u00e9 que na volta seguinte os dois tamb\u00e9m param. Ap\u00f3s a janela de paradas as posi\u00e7\u00f5es s\u00e3o reestabelecidas com Sammarone (1o), Jeferson (2o), Brock (3o), Leonardo (4o), Thiago (5o), Jonatan (6o), Cac\u00e1 (7o) e Menescal (8o). Sponta, que tinha se envolvido em um acidente na 1a volta e chegou a ser \u00faltimo, havia antecipado sua parada para a 6a volta e j\u00e1 figurava na 9a posi\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Apesar de ter conseguido uma certa vantagem para Jeferson, a exemplo do que ocorreu na etapa passada em Laguna Seca, na 16a volta Sammarone se envolve em um incidente com o retardat\u00e1rio Helder M\u00fcller, perde tempo e tamb\u00e9m a 1a posi\u00e7\u00e3o para Jeferson. A partir da\u00ed ele pisa fundo, encosta e luta para recuperar a lideran\u00e7a. Com a briga, Brock come\u00e7a a tirar a diferen\u00e7a para os dois primeiros. No in\u00edcio da 23a volta Jeferson comete um erro na curva 1, e Sammarone recupera a posi\u00e7\u00e3o. S\u00f3 que um pouco mais a frente \u00e9 a vez de Sammarone vacilar, permitindo que Jeferson encoste e ataque, retomando a lideran\u00e7a. Brock j\u00e1 estava encostado nos dois, mas na volta seguinte tamb\u00e9m vacila e perde o contato com a briga.<\/span><\/p>\n<p><span style=\"color: #000000;\">Enquanto isso as disputas seguem acirradas nos pelot\u00f5es intermedi\u00e1rios. Durante a 19a volta Edilson Carneiro recupera a 15a posi\u00e7\u00e3o sobre Beto M\u00fcller, que vinha fazendo uma corrida de recupera\u00e7\u00e3o. Na 21a volta Sponta assume a 8a posi\u00e7\u00e3o sobre Menescal, enquanto pela 10a posi\u00e7\u00e3o a disputa se prolonga por v\u00e1rias voltas entre Andr\u00e9 Castanheira e Gustavo Breves. Castanheira mant\u00e9m a posi\u00e7\u00e3o no fim, enquanto Gustavo ainda \u00e9 ultrapassado por Maurino J\u00fanior na \u00faltima volta.<\/span><br \/>\n<span style=\"color: #000000;\"> <\/span><\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><span style=\"color: #000000;\">No fim, Jeferson Richart (Racers4Fun) resiste aos ataques finais e conquista a vit\u00f3ria. Bruno Sammarone (Zeto Racing) termina em 2o e Ernesto Brock (Racers4Fun) fica com a 3a posi\u00e7\u00e3o. Repetindo o que aconteceu com Sakita em Laguna Seca, em Ober\u00e1 Jeferson vence em todas as 4 categorias que disputou. Ser\u00e1 que teremos um novo vencedor in\u00e9dito em Denver?<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Confiram a pontua\u00e7\u00e3o do campeonato e o replay da corrida no menu acima.<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #000000;\">At\u00e9 a pr\u00f3xima etapa com mais emo\u00e7\u00f5es em Denver, dia 24.03.2011! a VPG te espera l\u00e1!<\/span><\/strong><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Jeferson Richart brilha em Ober\u00e1 pela 3a etapa da Challenge! Numa corrida muito disputada, com os 3 primeiros trocando de posi\u00e7\u00f5es durante a prova e sempre andando bem pr\u00f3ximos, Jeferson Richart se torna o 3o vencedor diferente nas 3 etapas ocorridas da categoria Challenge, e assume a lideran\u00e7a do campeonato. Como acontece frequentemente, nos treinos [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2374","post","type-post","status-publish","format-standard","hentry","category-vpg-2011"],"_links":{"self":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/2374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/comments?post=2374"}],"version-history":[{"count":20,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/2374\/revisions"}],"predecessor-version":[{"id":2384,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/posts\/2374\/revisions\/2384"}],"wp:attachment":[{"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/media?parent=2374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/categories?post=2374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ligavpg.com\/blog\/wp-json\/wp\/v2\/tags?post=2374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}